{"id":338184,"date":"2024-07-04T10:35:14","date_gmt":"2024-07-04T09:35:14","guid":{"rendered":"https:\/\/wp.edirex.ch\/annuaire\/index.php\/annonce\/borgatta-menuiserie-sa\/"},"modified":"2025-04-23T08:50:10","modified_gmt":"2025-04-23T07:50:10","slug":"borgatta-menuiserie-sa","status":"publish","type":"listing","link":"https:\/\/edirex.ch\/annuaire\/annonce\/borgatta-menuiserie-sa\/","title":{"rendered":"Borgatta Menuiserie SA"},"content":{"rendered":"<h2>Borgatta Menuiserie SA : l&rsquo;art du bois \u00e0 l&rsquo;\u00e9tat pur<\/h2>\n<h2>Une histoire riche d&rsquo;h\u00e9ritage<\/h2>\n<p>Depuis 1932, Borgatta Menuiserie, entreprise familiale ancr\u00e9e au c\u0153ur de la r\u00e9gion du haut lac L\u00e9man, fleure bon le savoir-faire artisanal et le travail bien fait. D&rsquo;une petite menuiserie \u00e9tablie par Pierre Borgatta dans sa grange \u00e0 Chernex, la soci\u00e9t\u00e9 a \u00e9volu\u00e9 en un acteur cl\u00e9 des r\u00e9alisations en bois dans la r\u00e9gion. Forte d&rsquo;une tradition transmise de p\u00e8re en fils, chaque g\u00e9n\u00e9ration a su apporter innovation et modernit\u00e9 tout en pr\u00e9servant l&rsquo;h\u00e9ritage pr\u00e9cieux des techniques traditionnelles.<\/p>\n<h2>Un atelier moderne et performant<\/h2>\n<p>Implant\u00e9 \u00e0 Villeneuve, notre atelier de 400 m2 est \u00e9quip\u00e9 de technologies de pointe, y compris une machine \u00e0 commande num\u00e9rique, garantissant ainsi une qualit\u00e9 optimale dans chacune de nos cr\u00e9ations. Gr\u00e2ce \u00e0 un parc machine innovant et des espaces d\u00e9di\u00e9s aux diff\u00e9rentes \u00e9tapes de fabrication, Borgatta Menuiserie assure une pr\u00e9cision in\u00e9gal\u00e9e dans ses projets complexes. Qu&rsquo;il s&rsquo;agisse de la fabrication de fen\u00eatres en bois-m\u00e9tal, d&rsquo;agencements personnalis\u00e9s ou de la confection de meubles uniques, notre atelier est une fabrique d&rsquo;excellence.<\/p>\n<h2>Une \u00e9quipe soud\u00e9e et comp\u00e9tente<\/h2>\n<p>Compos\u00e9e de six collaborateurs engag\u00e9s, notre \u00e9quipe allie comp\u00e9tences techniques et cr\u00e9ativit\u00e9, veillant \u00e0 l&rsquo;\u00e9panouissement de chaque projet. Titulaires de certificats f\u00e9d\u00e9raux de capacit\u00e9, nos artisans sont encadr\u00e9s par un bureau technique aux comp\u00e9tences f\u00e9d\u00e9rales, gage de s\u00e9rieux et de rigueur. Le perfectionnement continu fait partie int\u00e9grante de notre philosophie, ce qui nous permet de maintenir un niveau d&rsquo;expertise \u00e9lev\u00e9 tout en cultivant un environnement propice \u00e0 l&rsquo;innovation.<\/p>\n<h2>Un service sur-mesure pour des am\u00e9nagements personnalis\u00e9s<\/h2>\n<p>Borgatta Menuiserie s&rsquo;illustre par la diversit\u00e9 de ses prestations. Portes d&rsquo;entr\u00e9e grandioses, armoires murales ing\u00e9nieuses, biblioth\u00e8ques r\u00e9tro-\u00e9clair\u00e9es : toutes nos \u0153uvres r\u00e9sultent d&rsquo;une concertation \u00e9troite avec nos clients pour r\u00e9pondre \u00e0 leurs souhaits les plus sp\u00e9cifiques. Tout commence par une rencontre enthousiaste, une esquisse, puis la sophistication de plans avant de donner vie \u00e0 vos id\u00e9es avec pr\u00e9cision et soin. Notre approche flexible nous permet de travailler sur des styles contemporains comme traditionnels, dotant chaque espace d&rsquo;une signature esth\u00e9tique unique.<\/p>\n<h2>Des r\u00e9alisations embl\u00e9matiques pour penser demain<\/h2>\n<p>Nos projets, qu&rsquo;ils soient classiques ou avant-gardistes, incarnent notre passion pour le bois et le design. \u00c0 l&rsquo;image de la Maison de l&rsquo;Ours \u00e0 Montreux, o\u00f9 nous avons transform\u00e9 les cuisines et les salles de bains en sanctuaires \u00e9l\u00e9gants et fonctionnels, Borgatta Menuiserie se distingue par des solutions innovantes et harmonieuses. Nos fen\u00eatres sur-mesure, avec leur coefficient thermique exemplaire, attestent de notre engagement envers l&rsquo;environnement et les monuments historiques, offrant une parfaite alliance entre tradition et modernit\u00e9.<\/p>\n","protected":false},"author":17,"featured_media":349640,"comment_status":"open","ping_status":"closed","template":"","meta":[],"listing_category":[1512],"event_category":[],"service_category":[],"rental_category":[],"classifieds_category":[],"listing_feature":[],"region":[],"class_list":["post-338184","listing","type-listing","status-publish","has-post-thumbnail","hentry","listing_category-menuiserie-cuisine-parquet-charpente"],"_links":{"self":[{"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/listing\/338184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/listing"}],"about":[{"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/comments?post=338184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/media\/349640"}],"wp:attachment":[{"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/media?parent=338184"}],"wp:term":[{"taxonomy":"listing_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/listing_category?post=338184"},{"taxonomy":"event_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/event_category?post=338184"},{"taxonomy":"service_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/service_category?post=338184"},{"taxonomy":"rental_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/rental_category?post=338184"},{"taxonomy":"classifieds_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/classifieds_category?post=338184"},{"taxonomy":"listing_feature","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/listing_feature?post=338184"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/region?post=338184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}