{"id":338408,"date":"2024-07-04T10:35:53","date_gmt":"2024-07-04T09:35:53","guid":{"rendered":"https:\/\/wp.edirex.ch\/annuaire\/index.php\/annonce\/eausolair-sarl\/"},"modified":"2025-04-30T08:51:37","modified_gmt":"2025-04-30T07:51:37","slug":"eausolair-sarl","status":"publish","type":"listing","link":"https:\/\/edirex.ch\/annuaire\/annonce\/eausolair-sarl\/","title":{"rendered":"EauSolAir S\u00e0rl"},"content":{"rendered":"<section>\n<h2>Bienvenue sur cette page d\u00e9di\u00e9e \u00e0 EauSolAir S\u00e0rl<\/h2>\n<p>Cette page est actuellement en attente de validation ou de mise \u00e0 jour par l\u2019entreprise concern\u00e9e.<br \/>\nSi vous \u00eates le repr\u00e9sentant ou le propri\u00e9taire de <strong>EauSolAir S\u00e0rl<\/strong>,<br \/>\nnous vous invitons \u00e0 prendre en main votre pr\u00e9sence sur notre annuaire.<\/p>\n<p>Chez <strong>edirex.ch<\/strong>, nous offrons aux entrepreneurs la possibilit\u00e9 de s\u2019inscrire<br \/>\ngratuitement et de personnaliser les informations affich\u00e9es pour leur entreprise. Une page compl\u00e8te<br \/>\net \u00e0 jour vous permet de renforcer votre visibilit\u00e9 et d\u2019attirer de nouveaux clients.<\/p>\n<p>Pour g\u00e9rer ou modifier cette page, rien de plus simple ! Cliquez sur le bouton<br \/>\n<em>\u00ab R\u00e9clamer cette page \u00bb<\/em> et remplissez le formulaire d\u00e9di\u00e9. Une fois votre demande valid\u00e9e,<br \/>\nvous pourrez :<\/p>\n<ul>\n<li>Ajouter des d\u00e9tails sur vos services ou produits ;<\/li>\n<li>Mettre \u00e0 jour vos horaires et coordonn\u00e9es ;<\/li>\n<li>Int\u00e9grer des photos ou un logo ;<\/li>\n<li>Et bien plus encore.<\/li>\n<\/ul>\n<p>N\u2019attendez plus pour mettre en avant votre activit\u00e9 ! Rendez-vous sur<br \/>\n<a>edirex.ch\/annuaire<\/a> pour compl\u00e9ter votre profil<br \/>\nen quelques clics.<\/p>\n<p><strong>Une pr\u00e9sence en ligne accessible et gratuite pour tous les entrepreneurs suisses.<\/strong><\/p>\n<\/section>\n","protected":false},"author":1,"featured_media":349772,"comment_status":"open","ping_status":"closed","template":"","meta":[],"listing_category":[1517],"event_category":[],"service_category":[],"rental_category":[],"classifieds_category":[],"listing_feature":[],"region":[],"class_list":["post-338408","listing","type-listing","status-publish","has-post-thumbnail","hentry","listing_category-installation-solaire"],"_links":{"self":[{"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/listing\/338408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/listing"}],"about":[{"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/comments?post=338408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/media\/349772"}],"wp:attachment":[{"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/media?parent=338408"}],"wp:term":[{"taxonomy":"listing_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/listing_category?post=338408"},{"taxonomy":"event_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/event_category?post=338408"},{"taxonomy":"service_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/service_category?post=338408"},{"taxonomy":"rental_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/rental_category?post=338408"},{"taxonomy":"classifieds_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/classifieds_category?post=338408"},{"taxonomy":"listing_feature","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/listing_feature?post=338408"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/region?post=338408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}