{"id":386866,"date":"2025-04-25T19:58:13","date_gmt":"2025-04-25T18:58:13","guid":{"rendered":"https:\/\/edirex.ch\/annuaire\/?post_type=listing&#038;p=386866"},"modified":"2025-05-26T16:21:02","modified_gmt":"2025-05-26T15:21:02","slug":"denn-morina-sarl","status":"publish","type":"listing","link":"https:\/\/edirex.ch\/annuaire\/annonce\/denn-morina-sarl\/","title":{"rendered":"Denn Morina S\u00e0rl"},"content":{"rendered":"<section>\n<h2>Bienvenue sur cette page d\u00e9di\u00e9e \u00e0 Denn Morina S\u00e0rl<\/h2>\n<p>Cette page est actuellement en attente de validation ou de mise \u00e0 jour par l\u2019entreprise concern\u00e9e.<br \/>\nSi vous \u00eates le repr\u00e9sentant ou le propri\u00e9taire de <strong>Denn Morina S\u00e0rl<\/strong>,<br \/>\nnous vous invitons \u00e0 prendre en main votre pr\u00e9sence sur notre annuaire.<\/p>\n<p>Chez <strong>edirex.ch<\/strong>, nous offrons aux entrepreneurs la possibilit\u00e9 de s\u2019inscrire<br \/>\ngratuitement et de personnaliser les informations affich\u00e9es pour leur entreprise. Une page compl\u00e8te<br \/>\net \u00e0 jour vous permet de renforcer votre visibilit\u00e9 et d\u2019attirer de nouveaux clients.<\/p>\n<p>Pour g\u00e9rer ou modifier cette page, rien de plus simple ! Cliquez sur le bouton<br \/>\n<em>\u00ab R\u00e9clamer cette page \u00bb<\/em> et remplissez le formulaire d\u00e9di\u00e9. Une fois votre demande valid\u00e9e,<br \/>\nvous pourrez :<\/p>\n<ul>\n<li>Ajouter des d\u00e9tails sur vos services ou produits ;<\/li>\n<li>Mettre \u00e0 jour vos horaires et coordonn\u00e9es ;<\/li>\n<li>Int\u00e9grer des photos ou un logo ;<\/li>\n<li>Et bien plus encore.<\/li>\n<\/ul>\n<p>N\u2019attendez plus pour mettre en avant votre activit\u00e9 ! Rendez-vous sur<br \/>\n<a href=\"https:\/\/edirex.ch\/annuaire\" target=\"_blank\" rel=\"noopener\">edirex.ch\/annuaire<\/a> pour compl\u00e9ter votre profil<br \/>\nen quelques clics.<\/p>\n<p><strong>Une pr\u00e9sence en ligne accessible et gratuite pour tous les entrepreneurs suisses.<\/strong><\/p>\n<\/section>\n","protected":false},"author":1,"featured_media":388281,"comment_status":"open","ping_status":"closed","template":"","meta":[],"listing_category":[1513],"event_category":[],"service_category":[],"rental_category":[],"classifieds_category":[],"listing_feature":[],"region":[],"class_list":["post-386866","listing","type-listing","status-publish","has-post-thumbnail","hentry","listing_category-maconnerie-carrelage"],"_links":{"self":[{"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/listing\/386866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/listing"}],"about":[{"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/comments?post=386866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/media\/388281"}],"wp:attachment":[{"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/media?parent=386866"}],"wp:term":[{"taxonomy":"listing_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/listing_category?post=386866"},{"taxonomy":"event_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/event_category?post=386866"},{"taxonomy":"service_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/service_category?post=386866"},{"taxonomy":"rental_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/rental_category?post=386866"},{"taxonomy":"classifieds_category","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/classifieds_category?post=386866"},{"taxonomy":"listing_feature","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/listing_feature?post=386866"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/edirex.ch\/annuaire\/wp-json\/wp\/v2\/region?post=386866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}